{"id":2423,"date":"2020-08-26T19:41:37","date_gmt":"2020-08-26T19:41:37","guid":{"rendered":"http:\/\/52.254.6.109\/blog-lc?p=2423"},"modified":"2024-09-10T16:57:25","modified_gmt":"2024-09-10T19:57:25","slug":"acertar-12-numeros-lotofacil-independencia","status":"publish","type":"post","link":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/","title":{"rendered":"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?"},"content":{"rendered":"<p>Quando os concursos especiais se aproximam, muitos apostadores tentam a sorte. N\u00e3o \u00e9 todo dia, afinal, que eles podem concorrer a pr\u00eamios t\u00e3o altos. Com isso, surgem novas d\u00favidas: <a href=\"https:\/\/lottocap.com.br\/blog\/como-apostar-na-lotofacil-da-independencia\/\">como jogar<\/a>, quais s\u00e3o as chances de ganhar e quest\u00f5es referentes \u00e0 premia\u00e7\u00e3o, como, por exemplo, se acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia vale pr\u00eamio.<\/p>\n<p>Se voc\u00ea \u00e9 um dos que n\u00e3o sabem se o <strong>acerto de 12 dezenas na Lotof\u00e1cil da Independ\u00eancia vale pr\u00eamio<\/strong>, hoje vamos solucionar essa d\u00favida. Abaixo, voc\u00ea vai entender como \u00e9 feita a distribui\u00e7\u00e3o de pr\u00eamios do concurso especial para que n\u00e3o tenha mais problemas na hora de conferir se ganhou ou n\u00e3o.<\/p>\n<h2><strong>Acertando 12 pontos na Lotof\u00e1cil da Independ\u00eancia ganho alguma coisa?<\/strong><\/h2>\n<p>A resposta que voc\u00ea estava esperando \u00e9 positiva! Sim, os apostadores que fazem 12 pontos na Lotof\u00e1cil da Independ\u00eancia s\u00e3o premiados e levam um dinheiro para a casa. Isso porque as <a href=\"https:\/\/lottocap.com.br\/blog\/quantos-numeros-acertar-lotofacil\/\">faixas de premia\u00e7\u00e3o s\u00e3o iguais \u00e0s dos concursos regulares<\/a>.<\/p>\n<p>Obviamente, o pr\u00eamio n\u00e3o \u00e9 o mais alto da loteria. Acertando 12 n\u00fameros, voc\u00ea leva a premia\u00e7\u00e3o correspondente a essa quantidade de acertos. Para levar o valor principal, \u00e9 necess\u00e1rio acertar todas as dezenas extra\u00eddas no concurso, ou seja, 15 n\u00fameros.<\/p>\n<p>Mesmo assim, a Lotof\u00e1cil segue sendo um dos concursos mais f\u00e1ceis do pa\u00eds em se conseguir algum pr\u00eamio. E as chances de conquistar um pr\u00eamio maior &#8211; e at\u00e9 mesmo de levar o valor m\u00e1ximo &#8211; ainda s\u00e3o muito mais altas se comparadas com outras loterias. Portanto, n\u00e3o tem motivo para desanimar:<\/p>\n<div class=\"lotto-meio-da-materia\" style=\"text-align: center;\" id=\"lotto-919066934\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2025\/04\/Loteria-Mega-300-x-250-px.png\" alt=\"Banner do LottoCap: Jogue na Mega-Sena, aposte agora!\"  class=\"no-lazyload\" width=\"300\" height=\"250\"   \/><\/div><h2>Quanto ganha acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia?<\/h2>\n<p>Nesta faixa de premia\u00e7\u00e3o, os ganhos ainda s\u00e3o fixos e o valor\u00a0 correspondente na faixa de 12 dezenas corretas \u00e9 de\u00a0 4 vezes o valor da aposta simples.<\/p>\n<p>Ou seja, quem acerta 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia ganha R$ 12,00.<\/p>\n<p>N\u00e3o \u00e9 uma baita bolada, por\u00e9m voc\u00ea vai ter o valor da sua aposta de volta, bem como ainda vai multiplic\u00e1-lo por 4 vezes.<\/p>\n<p>Acertar 12 dezenas com uma aposta simples \u00e9 de uma em 60. Aumentando as dezenas apostadas aumenta tamb\u00e9m as suas probabilidades.<\/p>\n<h3>Tabela completa de probabilidades de acerto de 12 n\u00fameros por dezenas apostadas<\/h3>\n<p>Apostando 15 dezenas &#8211; 1 em 60<\/p>\n<p>Apostando 16 dezenas- 1 em 21<\/p>\n<p>Apostando 17 dezenas &#8211; 1 em 9<\/p>\n<p>Apostando 18 dezenas- 1 em 5<\/p>\n<p>Apostando 19 dezenas &#8211; 1 em 3,2<\/p>\n<p>Apostando 20 dezenas &#8211; 1 em 2,6<\/p>\n<p>Como pode ver, aumentando as dezenas, aumentam-se tamb\u00e9m as chances de acerto. No entanto, \u00e9 importante notar que <a href=\"https:\/\/lottocap.com.br\/blog\/qual-o-valor-da-lotofacil-da-independencia-saiba-o-preco-das-apostas\/\">os valores de apostas tamb\u00e9m se elevam<\/a>.<\/p>\n<h2>Curiosidades sobre quem acerta 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia<\/h2>\n<p>Assim como as faixa de 11 e 13 acertos, a faixa de 12 n\u00fameros \u00e9 fixa. Veja abaixo os valores pagos ao longo dos anos e tamb\u00e9m a evolu\u00e7\u00e3o do n\u00famero de ganhadores ano ap\u00f3s ano, veja os dados mais abaixo.<\/p>\n<h3>Valores de pr\u00eamios de 12 Acertos da Lotof\u00e1cil da Independ\u00eancia ao longo dos anos<\/h3>\n<p>Como o valor de 12 acertos depende do valor de aposta da Lotof\u00e1cil da Independ\u00eancia, quando o pre\u00e7o de aposta da loteria sobe, o valor que retorna para o apostador que acertar nessa faixa de premia\u00e7\u00e3o tamb\u00e9m vai subir.<\/p>\n<p>O valor do pr\u00eamio para quem acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia \u00e9 de 4 vezes o valor da aposta, assim sendo, a evolu\u00e7\u00e3o da premia\u00e7\u00e3o \u00e9 a seguinte:<\/p>\n<p>Entre 2012 e 2013: R$ 5,00<\/p>\n<p>Em 2014: R$ 6,00<\/p>\n<p>Entre 2015 e 2019: R$ 8,00<\/p>\n<p>Entre 2020 e 2022: R$ 10,00<\/p>\n<p>Em 2023: R$ 12,00<\/p>\n<h3>Evolu\u00e7\u00e3o do n\u00famero de apostas vencedoras de 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia<\/h3>\n<p>Nesta faixa de premia\u00e7\u00e3o a quantidade de apostas vencedoras em cada concurso ainda fica em n\u00fameros bem elevados, confira abaixo a evolu\u00e7\u00e3o ano ap\u00f3s ano.<\/p>\n<p>Na primeira edi\u00e7\u00e3o, em 2012, tivemos 1,4 milh\u00f5es de vencedores.<\/p>\n<p>Entre 2013 e 2017 o n\u00famero de vencedores de 12 n\u00fameros ficou entre 1,7 milh\u00e3o e 2,4 milh\u00f5es.<\/p>\n<p>Entre 2018 e 2020 o n\u00famero d\u00e1 um leve salto e fica entre 2,5 milh\u00f5es e 2,7 milh\u00f5es nos 3 anos.<\/p>\n<p>Entre 2021 e 2023 h\u00e1 um novo salto, agora ficando entre 3,5 milh\u00f5es e 4,2 milh\u00f5es.<\/p>\n<div class=\"lotto-meio-da-materia-2\" style=\"text-align: center;\" id=\"lotto-1340233023\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2025\/04\/Loteria-Mega-300-x-250-px.png\" alt=\"Banner do LottoCap: Jogue na Mega-Sena, aposte agora!\"  class=\"no-lazyload\" width=\"300\" height=\"250\"   \/><\/div><h2><strong>Faixas de premia\u00e7\u00e3o e probabilidades da Lotof\u00e1cil da Independ\u00eancia<\/strong><\/h2>\n<p>Agora voc\u00ea sabe que, com 12 acertos, j\u00e1 leva um pr\u00eamio da Lotof\u00e1cil da Independ\u00eancia. Mas voc\u00ea sabia que nem \u00e9 necess\u00e1rio acertar essa quantidade de dezenas para conquistar algum valor no concurso? Isso mesmo! Quem faz <a href=\"https:\/\/lottocap.com.br\/blog\/acertar-11-numeros-na-lotofacil-da-independencia-ganha-premio-confira\/\">11 acertos tamb\u00e9m j\u00e1 leva um pr\u00eamio<\/a>.<\/p>\n<p>As faixas de premia\u00e7\u00e3o, portanto, come\u00e7am em 11 e v\u00e3o subindo at\u00e9 15 pontos. Quanto maior a quantidade de acertos, maior \u00e9 o pr\u00eamio conquistado no final. \u00c9 claro que <a href=\"https:\/\/lottocap.com.br\/blog\/probabilidade-lotofacil\/\">a probabilidade de acerto \u00e9 menor nas faixas superiores<\/a>, mas vamos mostrar como, de qualquer forma, elas continuam elevadas.<\/p>\n<p>A probabilidade de conquistar o pr\u00eamio m\u00ednimo, com 11 pontos, \u00e9 de 1 em 11 com uma aposta simples.<\/p>\n<p>Como j\u00e1 foi citado anteriormente, as chances de fazer os 12 acertos que estamos falando neste artigo s\u00e3o de 1 em 60 considerando o mesmo tipo de aposta.<\/p>\n<p>As outras faixas de pr\u00eamio, <a href=\"https:\/\/lottocap.com.br\/blog\/acertar-13-numeros-na-lotofacil-da-independencia-ganha-premio-confira\/\">13 n\u00fameros certos<\/a> e <a href=\"https:\/\/lottocap.com.br\/blog\/14-numeros-na-lotofacil-da-independencia-ganha-premio-confira\/\">14 dezenas sorteadas<\/a> tem probabilidade, respectivamente, de 1 para 692 e 1 para 21.792, como pode ver realmente fica mais dif\u00edcil.<\/p>\n<p>Se falarmos sobre o pr\u00eamio mais alto, as chances de ganhar com uma aposta simples s\u00e3o de 1 em 3.268.760. A princ\u00edpio este n\u00famero pode assustar um pouco, mas, ao fazermos a compara\u00e7\u00e3o com outros concursos, fica claro o motivo pelo qual esta loteria \u00e9 considerada uma das mais f\u00e1ceis de ganhar.<\/p>\n<p>As chances de ganhar o pr\u00eamio mais alto da Mega-Sena, por exemplo, s\u00e3o de 1 em 50.063.860, tanto nos concursos regulares quanto em sua edi\u00e7\u00e3o especial, a Mega da Virada. Isso quer dizer que na Lotof\u00e1cil a probabilidade de levar o primeiro pr\u00eamio \u00e9 mais de 15 vezes maior.<\/p>\n<p>O jogador tamb\u00e9m tem a possibilidade de <a href=\"https:\/\/lottocap.com.br\/blog\/quantos-numeros-posso-jogar-na-lotofacil-da-independencia-saiba-tudo\/\">usar mais dezenas em suas apostas<\/a> para aumentar as chances de ganhar. \u00c9 poss\u00edvel jogar com at\u00e9 20 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia. Nestes casos, por exemplo, a probabilidade de levar o pr\u00eamio mais alto passa a ser de 1 em 210.<\/p>\n<h2>Acertar 12 n\u00fameros na Lotof\u00e1cil regular ganha o mesmo que na Lotof\u00e1cil da Independ\u00eancia?<\/h2>\n<p>A resposta \u00e9 sim. Em ambos os casos a premia\u00e7\u00e3o fica na segunda faixa, ou seja ainda est\u00e1 na faixa de premia\u00e7\u00e3o fixa, que no caso de 12 acertos paga 4x o valor da aposta, que atualmente est\u00e1 em R$ 12,00.<\/p>\n<h2><strong>Um pouco mais sobre as faixas de premia\u00e7\u00e3o da Lotof\u00e1cil da Independ\u00eancia?<\/strong><\/h2>\n<p>Bom, voc\u00ea j\u00e1 sabe quantos pontos precisa fazer para<a href=\"https:\/\/lottocap.com.br\/blog\/como-ganhar-na-lotofacil-da-independencia-saiba-tudo-sobre-o-concurso\/\"> ganhar pr\u00eamios na Lotof\u00e1cil da Independ\u00eancia<\/a> e as chances disso acontecer. Que tal, ent\u00e3o, saber quanto voc\u00ea pode ganhar em cada quantidades de dezenas? Abaixo, vamos falar tudo sobre os valores de premia\u00e7\u00e3o do concurso especial da Caixa.<\/p>\n<p>Existem tr\u00eas faixas de premia\u00e7\u00e3o fixas, que n\u00e3o dependem de nenhum outro fator para determinar o valor conquistado. O pr\u00eamio ser\u00e1 sempre aquele, em qualquer ocasi\u00e3o. A faixa de 12 dezenas faz parte deste grupo.<\/p>\n<p>Quem acerta 11 n\u00fameros leva R$ 6,00, enquanto aqueles que fazem 12 ficam com R$ 12,00 como pr\u00eamio.<\/p>\n<p>Por \u00faltimo na parte de premia\u00e7\u00f5es fixas est\u00e1 a faixa de 13 dezenas. Quem faz essa quantidade de pontos leva R$ 30,00 no concurso.<\/p>\n<p>Nas faixas de 14 e 15 n\u00fameros, por\u00e9m, n\u00e3o \u00e9 poss\u00edvel determinar quanto o apostador pode ganhar. Nestes casos, o pr\u00eamio n\u00e3o \u00e9 fixo e depende do valor arrecadado no concurso, al\u00e9m do n\u00famero de ganhadores existentes nestas faixas, pois h\u00e1 uma divis\u00e3o do pr\u00eamio.<\/p>\n<p>\u00c9 nesta faixa de premia\u00e7\u00e3o vari\u00e1vel que a Lotof\u00e1cil da Independ\u00eancia fica diferente da Lotof\u00e1cil comum.\u00a0Depois de descontados os valores de premia\u00e7\u00f5es fixas, os apostadores que acertam 14 n\u00fameros ficam com 20% do total destinado \u00e0s premia\u00e7\u00f5es, enquanto os que fazem 15 pontos ficam com os 80% restantes.<\/p>\n<p>Lembrando que na loteria especial n\u00e3o h\u00e1 ac\u00famulo para o pr\u00f3ximo sorteio, isso significa que se n\u00e3o houver ganhadores na faixa de 15 n\u00fameros, os pr\u00eamios v\u00e3o ser divididos entre os ganhadores de 14 n\u00fameros, se n\u00e3o houver acertadores, (na remot\u00edssima possibilidade) vai para 13, depois de 12 e por \u00faltimo 11.<\/p>\n<p>Mesmo que n\u00e3o seja poss\u00edvel determinar com exatid\u00e3o o valor do pr\u00eamio principal, a Caixa sempre divulga uma estimativa. Basta ficar ligado e conferir os valores divulgados pr\u00f3ximos de cada sorteio anual do concurso.<\/p>\n<p>Agora que voc\u00ea sabe que acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia vale pr\u00eamio, n\u00e3o deixe de tentar a sorte e concorrer a um valor milion\u00e1rio!<\/p>\n<div class=\"lotto-fim-da-materia\" style=\"text-align: center;\" id=\"lotto-121389407\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2025\/04\/Loteria-Mega-300-x-250-px.png\" alt=\"Banner do LottoCap: Jogue na Mega-Sena, aposte agora!\"  class=\"no-lazyload\" width=\"300\" height=\"250\"   \/><\/div>","protected":false},"excerpt":{"rendered":"<p>Veja todas as informa\u00e7\u00f5es sobre este concurso especial e descubra se ganhar\u00e1 um pr\u00eamio ao acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia.<\/p>\n","protected":false},"author":4,"featured_media":2378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[144,166],"class_list":["post-2423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-loterias","tag-lotofacil","tag-lotofacil-independencia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?<\/title>\n<meta name=\"description\" content=\"Veja todas as informa\u00e7\u00f5es sobre este concurso especial e descubra se ganhar\u00e1 um pr\u00eamio ao acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?\" \/>\n<meta property=\"og:description\" content=\"Dicas de Capitaliza\u00e7\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog LottoCap\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lottocap\/\" \/>\n<meta property=\"article:author\" content=\"qaa\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-26T19:41:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T19:57:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2020\/08\/Premio-para-12-acertos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"326\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guilherme Seabra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guilherme Seabra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/\"},\"author\":{\"name\":\"Guilherme Seabra\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#\\\/schema\\\/person\\\/82c7f34c05cd306571ca9d4e072b09e1\"},\"headline\":\"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?\",\"datePublished\":\"2020-08-26T19:41:37+00:00\",\"dateModified\":\"2024-09-10T19:57:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/\"},\"wordCount\":1479,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lottocap.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Premio-para-12-acertos.jpg\",\"keywords\":[\"lotof\u00e1cil\",\"lotofacil independ\u00eancia\"],\"articleSection\":[\"Loterias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/\",\"url\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/\",\"name\":\"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lottocap.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Premio-para-12-acertos.jpg\",\"datePublished\":\"2020-08-26T19:41:37+00:00\",\"dateModified\":\"2024-09-10T19:57:25+00:00\",\"description\":\"Veja todas as informa\u00e7\u00f5es sobre este concurso especial e descubra se ganhar\u00e1 um pr\u00eamio ao acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lottocap.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Premio-para-12-acertos.jpg\",\"contentUrl\":\"https:\\\/\\\/lottocap.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Premio-para-12-acertos.jpg\",\"width\":1300,\"height\":326},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/acertar-12-numeros-lotofacil-independencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog LottoCap\",\"item\":\"https:\\\/\\\/bloglottocap.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#website\",\"url\":\"https:\\\/\\\/bloglottocap.com\\\/\",\"name\":\"Blog LottoCap\",\"description\":\"Dicas de Capitaliza\u00e7\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bloglottocap.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#organization\",\"name\":\"LottoCap\",\"url\":\"https:\\\/\\\/bloglottocap.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lottocap.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/foto-perfil_fanpage_Prancheta-1.png\",\"contentUrl\":\"https:\\\/\\\/lottocap.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/foto-perfil_fanpage_Prancheta-1.png\",\"width\":440,\"height\":440,\"caption\":\"LottoCap\"},\"image\":{\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lottocap\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lottocap\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bloglottocap.com\\\/#\\\/schema\\\/person\\\/82c7f34c05cd306571ca9d4e072b09e1\",\"name\":\"Guilherme Seabra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/caa139f1123078a4ccfddfafdab89ebba31fbdd96f35475a5b8d5477181717f8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/caa139f1123078a4ccfddfafdab89ebba31fbdd96f35475a5b8d5477181717f8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/caa139f1123078a4ccfddfafdab89ebba31fbdd96f35475a5b8d5477181717f8?s=96&d=mm&r=g\",\"caption\":\"Guilherme Seabra\"},\"sameAs\":[\"qaa\",\"aa\",\"aaa\",\"guilherme@52.254.6.109\"],\"url\":\"https:\\\/\\\/bloglottocap.com\\\/author\\\/guilherme\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?","description":"Veja todas as informa\u00e7\u00f5es sobre este concurso especial e descubra se ganhar\u00e1 um pr\u00eamio ao acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/","og_locale":"pt_BR","og_type":"article","og_title":"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?","og_description":"Dicas de Capitaliza\u00e7\u00e3o","og_url":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/","og_site_name":"Blog LottoCap","article_publisher":"https:\/\/www.facebook.com\/lottocap\/","article_author":"qaa","article_published_time":"2020-08-26T19:41:37+00:00","article_modified_time":"2024-09-10T19:57:25+00:00","og_image":[{"width":1300,"height":326,"url":"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2020\/08\/Premio-para-12-acertos.jpg","type":"image\/jpeg"}],"author":"Guilherme Seabra","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guilherme Seabra","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/#article","isPartOf":{"@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/"},"author":{"name":"Guilherme Seabra","@id":"https:\/\/bloglottocap.com\/#\/schema\/person\/82c7f34c05cd306571ca9d4e072b09e1"},"headline":"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?","datePublished":"2020-08-26T19:41:37+00:00","dateModified":"2024-09-10T19:57:25+00:00","mainEntityOfPage":{"@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/"},"wordCount":1479,"commentCount":0,"publisher":{"@id":"https:\/\/bloglottocap.com\/#organization"},"image":{"@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/#primaryimage"},"thumbnailUrl":"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2020\/08\/Premio-para-12-acertos.jpg","keywords":["lotof\u00e1cil","lotofacil independ\u00eancia"],"articleSection":["Loterias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/","url":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/","name":"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?","isPartOf":{"@id":"https:\/\/bloglottocap.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/#primaryimage"},"image":{"@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/#primaryimage"},"thumbnailUrl":"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2020\/08\/Premio-para-12-acertos.jpg","datePublished":"2020-08-26T19:41:37+00:00","dateModified":"2024-09-10T19:57:25+00:00","description":"Veja todas as informa\u00e7\u00f5es sobre este concurso especial e descubra se ganhar\u00e1 um pr\u00eamio ao acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia.","breadcrumb":{"@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/#primaryimage","url":"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2020\/08\/Premio-para-12-acertos.jpg","contentUrl":"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2020\/08\/Premio-para-12-acertos.jpg","width":1300,"height":326},{"@type":"BreadcrumbList","@id":"https:\/\/bloglottocap.com\/acertar-12-numeros-lotofacil-independencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog LottoCap","item":"https:\/\/bloglottocap.com\/"},{"@type":"ListItem","position":2,"name":"Quanto paga acertar 12 n\u00fameros na Lotof\u00e1cil da Independ\u00eancia? Vale pr\u00eamio?"}]},{"@type":"WebSite","@id":"https:\/\/bloglottocap.com\/#website","url":"https:\/\/bloglottocap.com\/","name":"Blog LottoCap","description":"Dicas de Capitaliza\u00e7\u00e3o","publisher":{"@id":"https:\/\/bloglottocap.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bloglottocap.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/bloglottocap.com\/#organization","name":"LottoCap","url":"https:\/\/bloglottocap.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/bloglottocap.com\/#\/schema\/logo\/image\/","url":"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2019\/10\/foto-perfil_fanpage_Prancheta-1.png","contentUrl":"https:\/\/lottocap.com.br\/blog\/wp-content\/uploads\/2019\/10\/foto-perfil_fanpage_Prancheta-1.png","width":440,"height":440,"caption":"LottoCap"},"image":{"@id":"https:\/\/bloglottocap.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lottocap\/","https:\/\/www.instagram.com\/lottocap\/"]},{"@type":"Person","@id":"https:\/\/bloglottocap.com\/#\/schema\/person\/82c7f34c05cd306571ca9d4e072b09e1","name":"Guilherme Seabra","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/caa139f1123078a4ccfddfafdab89ebba31fbdd96f35475a5b8d5477181717f8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/caa139f1123078a4ccfddfafdab89ebba31fbdd96f35475a5b8d5477181717f8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/caa139f1123078a4ccfddfafdab89ebba31fbdd96f35475a5b8d5477181717f8?s=96&d=mm&r=g","caption":"Guilherme Seabra"},"sameAs":["qaa","aa","aaa","guilherme@52.254.6.109"],"url":"https:\/\/bloglottocap.com\/author\/guilherme\/"}]}},"_links":{"self":[{"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/posts\/2423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/comments?post=2423"}],"version-history":[{"count":10,"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/posts\/2423\/revisions"}],"predecessor-version":[{"id":16350,"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/posts\/2423\/revisions\/16350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/media\/2378"}],"wp:attachment":[{"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/media?parent=2423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/categories?post=2423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bloglottocap.com\/wp-json\/wp\/v2\/tags?post=2423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}